{"id":154242,"date":"2022-03-03T08:47:05","date_gmt":"2022-03-03T07:47:05","guid":{"rendered":"https:\/\/admin.skatedeluxe.com\/blog\/?p=154242"},"modified":"2022-03-03T12:10:59","modified_gmt":"2022-03-03T11:10:59","slug":"converse-cons-louie-lopez-pro-wear-test","status":"publish","type":"post","link":"https:\/\/skatedeluxe.com\/blog\/fr\/converse-cons-louie-lopez-pro-wear-test\/","title":{"rendered":"Converse Cons Louie Lopez Pro Wear Test"},"content":{"rendered":"<div class=\"row\">\r\n\t<div class=\"small-12 medium-12 large-12 columns\">\r\n\t\t<p>\r\n\t\t\t<strong>\r\n\t\t\t\tLa <a href=\"\/fr\/converse-cons-louie-lopez\">Converse Cons Louie Lopez Pro<\/a> est une chaussure de skate intemporelle qui incarne parfaitement le skate de Louie. Ni trop ni trop peu &#8211; juste ce qu&#8217;il faut pour garantir des performances maximales et un look \u00e9l\u00e9gant tout du long.\r\n\t\t\t<\/strong>\r\n\t\t<\/p>\r\n\r\n\r\n\t\t<img decoding=\"async\" src=\"\/blog\/wp-content\/uploads\/2022\/02\/converse-cons-loui-lopez-wear-test-09.jpg\" alt=\"Converse Cons Louie Lopez Pro Test Review\" style=\"margin-bottom: 1em;\">\r\n\r\n\t\t<h2 style=\"margin-bottom: 1em;\">\r\n\t\t\tPremi\u00e8re impression et coupe de la Converse Cons Louie Lopez\r\n\t\t<\/h2>\r\n\t<\/div>\r\n<\/div>\r\n\r\n<div class=\"row\">\r\n\t<div class=\"small-12 medium-6 columns\">\r\n\t\t<p>\r\n\t\t\tLa premi\u00e8re chose que j&#8217;ai remarqu\u00e9e \u00e0 propos de la chaussure, c&#8217;est qu&#8217;elle est vraiment tr\u00e8s simple. \u00c9quip\u00e9 uniquement des fonctionnalit\u00e9s les plus n\u00e9cessaires, le mod\u00e8le a une silhouette tr\u00e8s agr\u00e9able et \u00e9pur\u00e9e. Au pied, la Louie Lopez a l&#8217;air assez fine.\r\n\t\t<\/p>\r\n\t\t\t<img decoding=\"async\" src=\"\/blog\/wp-content\/uploads\/2022\/02\/converse-cons-loui-lopez-wear-test-01.jpg\" alt=\"Converse Cons Louie Lopez Pro Test Review\" style=\"margin-bottom: 1em;\">\r\n\t\t<p>\r\n\t\t\tLa seule caract\u00e9ristique quelque peu accrocheuse est le lettrage dor\u00e9 sur le c\u00f4t\u00e9. Cependant, lorsque vous regardez la chaussure d&#8217;en haut, vous ne le remarquez pas, donc je n&#8217;ai pas trouv\u00e9 le lettrage emb\u00eatant, mais plut\u00f4t un petit bonus.\r\n\t\t<\/p>\r\n\t<\/div>\r\n\t<div class=\"small-12 medium-6 large-6 columns\">\r\n\t\t<p>\r\n\t\t\tLa Converse Cons Louie Lopez Pro a une coupe confortable et n&#8217;est pas trop serr\u00e9e au pied. \u00c9tant donn\u00e9 que les chaussures Converse Cons taillent g\u00e9n\u00e9ralement un peu plus petites, je vous conseille d&#8217;acheter une taille plus grande. En fait, je porte du EU 43 et j&#8217;ai des pieds assez larges. Dans un EU 44, le Louie Lopez Pro me va parfaitement. Sur la page de d\u00e9tail de l&#8217;article dans le shop, vous trouverez plus d&#8217;informations sur la s\u00e9lection de chaussures de skate Cons.\r\n\t\t<\/p>\r\n\t\t<img decoding=\"async\" src=\"\/blog\/wp-content\/uploads\/2022\/02\/converse-cons-loui-lopez-wear-test-08.jpg\" alt=\"Converse Cons Louie Lopez Pro Test Review\" style=\"margin-bottom: 1em;\">\r\n\t\t<p>\r\n\t\t\tJe n&#8217;ai eu besoin d&#8217;aucun temps d&#8217;adaptation avec la Lopez Pro et j&#8217;ai trouv\u00e9 la chaussure confortable d\u00e8s le premier instant. &#8220;Tout droit sorti de la bo\u00eete&#8221;, j&#8217;ai tout de suite eu le sentiment d&#8217;avoir port\u00e9 la chaussure depuis d\u00e9j\u00e0 plusieurs jours. \r\n\t\t<\/p>\r\n\t<\/div>\r\n<\/div>\r\n\t<div class=\"row\">\r\n\t<div class=\"small-12 medium-12 columns\">\r\n\t\t<h3>\r\n\t\t\tBoardfeel, Adh\u00e9rence &#038; Co &#8211; la Louie Lopez Pro dans le test\r\n\t\t<\/h3>\r\n\t<\/div>\r\n\t<div class=\"small-12 medium-6 columns\">\r\n\t\t<p>\r\n\t\t\tLa premi\u00e8re session avec les Louie Lopez Pro de Converse Cons aux pieds m&#8217;a vraiment surpris positivement. J&#8217;ai imm\u00e9diatement eu l&#8217;impression que j&#8217;avais skat\u00e9 la chaussure depuis plusieurs semaines et que je n&#8217;avais m\u00eame pas besoin de m&#8217;y habituer.\r\n\t\t<\/p>\r\n\t\t<img decoding=\"async\" src=\"\/blog\/wp-content\/uploads\/2022\/02\/Converse-Cons-Louie-Lopez-Wear-Test-used.jpg\" alt=\"Converse Cons Louie Lopez Pro Test Review\" style=\"margin-bottom: 1em;\">\r\n\t\t<p>\r\n\t\t\tLe boardfeel (sensations avec la planche) est extraordinairement bon. \u00c0 tout moment, j&#8217;ai eu le sentiment d&#8217;avoir suffisamment d&#8217;amorti et de s\u00e9curit\u00e9 lors d&#8217;impacts l\u00e9g\u00e8rement plus durs. Je n&#8217;avais pas de semelles douloureuses ou contusionn\u00e9es apr\u00e8s aucune de mes sessions. La semelle int\u00e9rieure amovible OrthoLite avec unit\u00e9 Nike Zoom Air fait ici du bon travail. \r\n\t\t<\/p>\r\n\r\n\t\t\r\n\t<\/div>\r\n\t<div class=\"small-12 medium-6 columns\">\r\n\r\n\t\t<p>\r\n\t\t\tL&#8217;adh\u00e9rence de la Converse Cons Louie Lopez Pro ne pourrait pas \u00eatre meilleure non plus. Je me suis senti en s\u00e9curit\u00e9 sur ma board \u00e0 tout moment et je n&#8217;avais jamais l&#8217;impression de &#8220;nager&#8221; dedans ou de perdre de l&#8217;adh\u00e9rence.\r\n\t\t<\/p>\r\n\t\t<img decoding=\"async\" src=\"\/blog\/wp-content\/uploads\/2022\/02\/converse-cons-louie-lopez-wear-test-used-3.jpg\" alt=\"Converse Cons Louie Lopez Pro Test Review\" style=\"margin-bottom: 1em; margin-top: 1em;\">\r\n\t\t<p>\r\n\t\t\tApr\u00e8s un certain temps, j&#8217;ai senti que la chaussure \u00e9tait devenue un peu plus souple et plus \u00e9lastique. Cependant, cela ne signifie pas que la chaussure s&#8217;est \u00e9largie et que j&#8217;ai perdu de l&#8217;adh\u00e9rence. Au contraire &#8211; j&#8217;ai plut\u00f4t eu le sentiment que la chaussure s&#8217;est parfaitement adapt\u00e9e \u00e0 mes pieds.\r\n\t\t<\/p>\r\n\t<\/div>\r\n<\/div>\r\n\r\n\t<div class=\"row\">\r\n\t<div class=\"small-12 medium-12 large-12 columns\">\r\n\r\n\t\t<h2>\r\n\t\t\tDurabilit\u00e9, comme vous le souhaitez &#8211; la Louie Lopez Pro\r\n\t\t<\/h2>\r\n\r\n\t<\/div>\r\n<\/div>\r\n\r\n<div class=\"row\">\r\n\t<div class=\"small-12 medium-6 columns\">\r\n\t\t<p>\r\n\t\t\tDans l&#8217;ensemble, j&#8217;ai skat\u00e9 la Louie Lopez Pro de Converse Cons pendant environ 30 \u00e0 35 heures et elle tient toujours tr\u00e8s bien. Mon skate \u00e0 ce moment-l\u00e0 consistait en un m\u00e9lange 50\/50 de courbes et de street.\r\n\t\t<\/p>\r\n\t\t<img decoding=\"async\" class=\"show-for-small-only\" src=\"\/blog\/wp-content\/uploads\/2022\/02\/converse-cons-loui-lopez-wear-test-03-story-format-2.jpg\" alt=\"Converse Cons Louie Lopez Pro Test Review\" style=\"margin-bottom: 1em; margin-top: 1em;\">\r\n\t\t<p>\r\n\t\t\tLe plus d&#8217;usure se situe \u00e0 l&#8217;avant de la semelle, mais la chaussure est encore loin d&#8217;avoir des coutures ouvertes ou quelque chose comme \u00e7a. Le logo Converse sur le c\u00f4t\u00e9 est un peu frott\u00e9, mais ne nuit en rien \u00e0 la performance. Les lacets ont tenu jusqu&#8217;\u00e0 pr\u00e9sent et ne montrent aucune usure. La semelle, \u00e0 part une petite zone \u00e9rafl\u00e9e, est toujours presque comme au premier jour.\r\n\t\t<\/p>\r\n\t<\/div>\r\n\r\n\t<div class=\"small-12 medium-6 show-for-medium-up columns\">\r\n\r\n\t\t<img decoding=\"async\" src=\"\/blog\/wp-content\/uploads\/2022\/02\/converse-cons-loui-lopez-wear-test-03-story-format-2.jpg\" alt=\"Converse Cons Louie Lopez Pro Test Review\" style=\"margin-bottom: 1em; margin-top: 1em;\">\r\n\t<\/div>\r\n<\/div>\r\n<hr>\r\n\r\n<h2>\r\n\tConclusion\r\n<\/h2>\r\n\r\n<div class=\"row\">\r\n\t<div class=\"small-12 medium-6 columns\">\r\n\t\t<p>\r\n\t\t\tHonn\u00eatement &#8211; je voudrais porter \u00e0 nouveau la chaussure et je le ferai tr\u00e8s probablement. Le mod\u00e8le Pro Louie Lopez est disponible dans une vari\u00e9t\u00e9 de styles : du daim, de la toile au cuir lisse et une version interm\u00e9diaire. Je peux bien imaginer que les diff\u00e9rents mod\u00e8les ne sont en aucun cas inf\u00e9rieurs les uns aux autres et ont toujours un haut niveau de qualit\u00e9 et de durabilit\u00e9.\r\n\t\t<\/p>\r\n\t<\/div>\r\n\t<div class=\"small-12 medium-6 columns\">\r\n\t\t<p>\r\n\t\t\tLe seul point n\u00e9gatif que je peux \u00e9voquer est le que la languette bouge un peu. \u00c9tant donn\u00e9 que la chaussure n&#8217;a pas de straps (\u00e9lastiques cousus sur le c\u00f4t\u00e9 de la languette d&#8217;une chaussure), la languette glisse soit vers la gauche, soit vers la droite. Je n&#8217;ai pas eu l&#8217;impression que cela affectait mon skate, cela me g\u00eanait seulement un peu visuellement. \r\n\t\t<\/p>\r\n\t<\/div>\r\n\t<div class=\"small-12 medium-12 columns\">\r\n\t\t<p>\r\n\t\t\tSi vous recherchez une chaussure de skate classique et simple qui vous durera longtemps et vous donnera beaucoup de sensations sur la board, la <a href=\"\/fr\/converse-cons-louie-lopez\">Converse Cons Louie Lopez Pro<\/a> est votre meilleur pari. \r\n\t\t<\/p>\r\n\t<\/div>\r\n\r\n\t<div class=\"small-12 medium-6 columns\">\r\n\t\t<p><span class=\"h4\">Les Pours <\/span><\/p>\r\n\t\t<ul>\r\n\t\t\t<li>Durabilit\u00e9<\/li>\r\n\t\t\t<li>Boardfeel<\/li>\r\n\t\t\t<li>Adh\u00e9rence<\/li>\r\n\t\t\t<li>Confort<\/li>\r\n\t\t<\/ul>\r\n\t<\/div>\r\n\t<div class=\"small-12 medium-6 columns\">\r\n\t\t<p><span class=\"h4\">Les Contres<\/span><\/p>\r\n\t\t<ul>\r\n\t\t\t<li>La languette bouge un peu<\/li>\r\n\t\t<\/ul>\r\n\t<\/div>\r\n<\/div>\r\n\r\n<div class=\"row\">\r\n\t<div class=\"small-12 medium-6 columns\">\r\n\t\t<a class=\"button-auto\" href=\"\/fr\/converse-cons-louie-lopez\" title=\"Acheter la Converse Cons Louie Lopez Pro\" style=\"margin-bottom: 1em;\">Acheter la Converse Cons Louie Lopez Pro<\/a>\r\n\t<\/div>\r\n\t<div class=\"small-12 medium-6 columns\">\r\n\t\t<a class=\"button-auto\" title=\"Plus de wear tests &#038; reviews\" href=\"\/blog\/fr\/category\/tests-de-produits\/\" style=\"margin-bottom: 1em;\">Plus de wear tests &#038; reviews<\/a>\r\n\t<\/div>\r\n<\/div>\r\n<div class=\"ShariffSC\" style=\"shariff-shop\"><div class=\"shariff\" data-url=\"https:\/\/skatedeluxe.com\/blog\/fr\/converse-cons-louie-lopez-pro-wear-test\/\" data-title=\"Converse Cons Louie Lopez Pro Wear Test\" data-services='[\"facebooklike\", \"facebook\"]' data-backend-url='\/shariff\/'><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>La Converse Cons Louie Lopez Pro est une chaussure de skate intemporelle qui incarne parfaitement le skate de Louie. Ni trop ni trop peu &#8211; juste ce qu&#8217;il faut pour garantir des performances maximales et un look \u00e9l\u00e9gant tout du long. Premi\u00e8re impression et coupe de la Converse Cons Louie Lopez La premi\u00e8re chose que <a class=\"read-more\" href=\"https:\/\/skatedeluxe.com\/blog\/fr\/converse-cons-louie-lopez-pro-wear-test\/\">[&#8230;]<\/a><\/p>\n","protected":false},"author":66,"featured_media":154201,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3336,5265],"tags":[],"class_list":["post-154242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produits","category-tests-de-produits"],"aioseo_notices":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/skatedeluxe.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/154242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skatedeluxe.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skatedeluxe.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skatedeluxe.com\/blog\/fr\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/skatedeluxe.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=154242"}],"version-history":[{"count":3,"href":"https:\/\/skatedeluxe.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/154242\/revisions"}],"predecessor-version":[{"id":154285,"href":"https:\/\/skatedeluxe.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/154242\/revisions\/154285"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skatedeluxe.com\/blog\/fr\/wp-json\/wp\/v2\/media\/154201"}],"wp:attachment":[{"href":"https:\/\/skatedeluxe.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=154242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skatedeluxe.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=154242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skatedeluxe.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=154242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}